{"id":26,"date":"2023-04-17T10:15:49","date_gmt":"2023-04-17T10:15:49","guid":{"rendered":"http:\/\/localhost\/yummye\/?page_id=26"},"modified":"2023-04-19T18:59:43","modified_gmt":"2023-04-19T18:59:43","slug":"menu","status":"publish","type":"page","link":"https:\/\/wpdemo.zcubethemes.com\/yummye\/menu\/","title":{"rendered":"Menu"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"26\" class=\"elementor elementor-26\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae2d5c1 elementor-section-full_width none-menu elementor-section-height-default elementor-section-height-default\" data-id=\"ae2d5c1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30d0643\" data-id=\"30d0643\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c79108 elementor-widget elementor-widget-Elementor-meal-widget\" data-id=\"8c79108\" data-element_type=\"widget\" data-widget_type=\"Elementor-meal-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Meal-area-start -->\r\n<section class=\"meal-select-section pt-50 pb-120 p-relative\">\r\n      <div class=\"animations-01\"><img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/an-img-01.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/an-img-01.png\" class=\"img\">     <\/div>\r\n   <div class=\"animations-02\"><img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/an-img-03.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/an-img-03.png\" class=\"img\">     <\/div>\r\n <div class=\"container\">\r\n        <div class=\"row\">\r\n            <div class=\"col-lg-12\">\r\n                <div class=\"section-title center-align mb-50 text-center wow fadeInDown animated\" data-animation=\"fadeInDown\" data-delay=\".4s\">\r\n                    <h5><span class=\"circle-left\"><img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/circle-left.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/circle-left.png\"><\/span> Our Menu<\/h5>\r\n                    <h2>\r\n                        What We Have In Here                     <\/h2>\r\n                     <p>  Proin consectetur non dolor vitae pulvinar. Pellentesque sollicitudin dolor eget neque viverra, sed interdum metus interdum. Cras lobortis pulvinar dolor, sit amet ullamcorper dolor iaculis vel <\/p>\r\n                <\/div>\r\n\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"row align-items-center\">\r\n            <div class=\"col-lg-12 col-md-12\">\r\n                <div class=\"populer-meal wow fadeInUp animated\" data-animation=\"fadeInUp\" data-delay=\".4s\">\r\n                    <ul>\r\n                          \r\n                         \r\n                        <li>\r\n                            <div class=\"meal-container\">\r\n                                <div class=\"meal-img\">\r\n                                      <img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/m-img01.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/>                                <\/div>\r\n                                <div class=\"meal-content\">\r\n                                    <h5>\r\n                                      New York Cheesecake                                    <\/h5>   \r\n                                    <p>Espresso and Light Layer of Crema<\/p>\n                                <\/div>\r\n                                <div class=\"line\">\r\n                                    <hr>\r\n                                <\/div>\r\n                                 <div class=\"meal-price\">\r\n                                      <strong>$12.90<\/strong>\r\n                                 <\/div>\r\n                            <\/div>\r\n                        <\/li>                       \r\n                          \r\n                         \r\n                        <li>\r\n                            <div class=\"meal-container\">\r\n                                <div class=\"meal-img\">\r\n                                      <img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/m-img02.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/>                                <\/div>\r\n                                <div class=\"meal-content\">\r\n                                    <h5>\r\n                                      Vegan Potato Waffles                                    <\/h5>   \r\n                                    <p>Espresso and Light Layer of Crema<\/p>\n                                <\/div>\r\n                                <div class=\"line\">\r\n                                    <hr>\r\n                                <\/div>\r\n                                 <div class=\"meal-price\">\r\n                                      <strong>$18.50<\/strong>\r\n                                 <\/div>\r\n                            <\/div>\r\n                        <\/li>                       \r\n                          \r\n                         \r\n                        <li>\r\n                            <div class=\"meal-container\">\r\n                                <div class=\"meal-img\">\r\n                                      <img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/m-img03.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/>                                <\/div>\r\n                                <div class=\"meal-content\">\r\n                                    <h5>\r\n                                      Rusty ice-cream                                    <\/h5>   \r\n                                    <p>Espresso and Light Layer of Crema<\/p>\n                                <\/div>\r\n                                <div class=\"line\">\r\n                                    <hr>\r\n                                <\/div>\r\n                                 <div class=\"meal-price\">\r\n                                      <strong>$12.00<\/strong>\r\n                                 <\/div>\r\n                            <\/div>\r\n                        <\/li>                       \r\n                          \r\n                         \r\n                        <li>\r\n                            <div class=\"meal-container\">\r\n                                <div class=\"meal-img\">\r\n                                      <img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/m-img04.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/>                                <\/div>\r\n                                <div class=\"meal-content\">\r\n                                    <h5>\r\n                                      Apple &#038; Pear Crumble                                    <\/h5>   \r\n                                    <p>Espresso and Light Layer of Crema<\/p>\n                                <\/div>\r\n                                <div class=\"line\">\r\n                                    <hr>\r\n                                <\/div>\r\n                                 <div class=\"meal-price\">\r\n                                      <strong>$19.00<\/strong>\r\n                                 <\/div>\r\n                            <\/div>\r\n                        <\/li>                       \r\n                          \r\n                         \r\n                        <li>\r\n                            <div class=\"meal-container\">\r\n                                <div class=\"meal-img\">\r\n                                      <img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/m-img05.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/>                                <\/div>\r\n                                <div class=\"meal-content\">\r\n                                    <h5>\r\n                                      Vegan Potato Waffles                                    <\/h5>   \r\n                                    <p>Espresso and Light Layer of Crema<\/p>\n                                <\/div>\r\n                                <div class=\"line\">\r\n                                    <hr>\r\n                                <\/div>\r\n                                 <div class=\"meal-price\">\r\n                                      <strong>$16.00<\/strong>\r\n                                 <\/div>\r\n                            <\/div>\r\n                        <\/li>                       \r\n                          \r\n                         \r\n                        <li>\r\n                            <div class=\"meal-container\">\r\n                                <div class=\"meal-img\">\r\n                                      <img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/m-img06.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/>                                <\/div>\r\n                                <div class=\"meal-content\">\r\n                                    <h5>\r\n                                      New York Cheesecake                                    <\/h5>   \r\n                                    <p>Espresso and Light Layer of Crema<\/p>\n                                <\/div>\r\n                                <div class=\"line\">\r\n                                    <hr>\r\n                                <\/div>\r\n                                 <div class=\"meal-price\">\r\n                                      <strong>$14.00<\/strong>\r\n                                 <\/div>\r\n                            <\/div>\r\n                        <\/li>                       \r\n                          \r\n                         \r\n                        <li>\r\n                            <div class=\"meal-container\">\r\n                                <div class=\"meal-img\">\r\n                                      <img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/m-img07.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/>                                <\/div>\r\n                                <div class=\"meal-content\">\r\n                                    <h5>\r\n                                      Apple &#038; Pear Crumble                                    <\/h5>   \r\n                                    <p>Espresso and Light Layer of Crema<\/p>\n                                <\/div>\r\n                                <div class=\"line\">\r\n                                    <hr>\r\n                                <\/div>\r\n                                 <div class=\"meal-price\">\r\n                                      <strong>$10.00<\/strong>\r\n                                 <\/div>\r\n                            <\/div>\r\n                        <\/li>                       \r\n                          \r\n                         \r\n                        <li>\r\n                            <div class=\"meal-container\">\r\n                                <div class=\"meal-img\">\r\n                                      <img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/m-img08.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/>                                <\/div>\r\n                                <div class=\"meal-content\">\r\n                                    <h5>\r\n                                      Rusty\u2019s ice-cream                                    <\/h5>   \r\n                                    <p>Espresso and Light Layer of Crema<\/p>\n                                <\/div>\r\n                                <div class=\"line\">\r\n                                    <hr>\r\n                                <\/div>\r\n                                 <div class=\"meal-price\">\r\n                                      <strong>$15.00<\/strong>\r\n                                 <\/div>\r\n                            <\/div>\r\n                        <\/li>                       \r\n                          \r\n                    <\/ul>\r\n\r\n                <\/div>\r\n            <\/div>        \r\n            <div class=\"col-md-12 text-center\">      \r\n                 <a href=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/menu\/\" class=\"btn mt-40 ss-btn smoth-scroll\">Discover More<\/a>\t\t\t\t\r\n            <\/div>\r\n        <\/div>\r\n\r\n    <\/div>\r\n<\/section>\r\n<!-- Meal-area-end -->\r\n\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef9379c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ef9379c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9dd8341\" data-id=\"9dd8341\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89aaf16 elementor-widget elementor-widget-Elementor_video_two\" data-id=\"89aaf16\" data-element_type=\"widget\" data-widget_type=\"Elementor_video_two.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t  <!-- video-area -->\r\n<section id=\"video\" class=\"video-area pt-150 pb-150 p-relative\" style=\"background-image:url('https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/video-bg.jpg'); background-repeat: no-repeat; background-position: center bottom; background-size:cover;background-attachment: fixed;\">\r\n<div class=\"container\">                   \r\n     <div class=\"row\">\r\n        <div class=\"col-12\">\r\n            <div class=\"s-video-wrap\">\r\n                <div class=\"s-video-content\">\r\n                    <a href=\"https:\/\/www.youtube.com\/watch?v=gyGsPlt06bo\" class=\"popup-video mb-50\"><img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/play-button.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/play-button.png\"><\/a>\r\n                <\/div>\r\n                <div class=\"section-title center-align text-center\">\r\n                       <h2> Watch Our Video<\/h2>\r\n                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<\/section>\r\n<!-- video-area-end -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6b5958 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f6b5958\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b70f430\" data-id=\"b70f430\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8830e04 elementor-widget elementor-widget-Elementor-testimonial\" data-id=\"8830e04\" data-element_type=\"widget\" data-widget_type=\"Elementor-testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n <!-- testimonial-area -->\r\n<section class=\"testimonial-area pt-120 pb-90 p-relative fix\">\r\n    <div class=\"container\">\r\n        <div class=\"row\">\r\n             <div class=\"col-lg-12\">\r\n                  <div class=\"section-title center-align mb-50 text-center\">\r\n                    <h5><span class=\"circle-left\"><img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/circle-left.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/circle-left.png\"><\/span> Our Online Shop<\/h5>\r\n                    <h2> What Our Clients Says <\/h2>\r\n                    <p>  Proin consectetur non dolor vitae pulvinar. Pellentesque sollicitudin dolor eget neque viverra, sed interdum metus interdum. Cras lobortis pulvinar dolor, sit amet ullamcorper dolor iaculis vel <\/p>\r\n                <\/div>\r\n\r\n            <\/div>\r\n            <div class=\"col-lg-12\">\r\n                <div class=\"testimonial-active\">\r\n                                                                  <div class=\"single-testimonial\">\r\n                         <div class=\"testi-author\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar.png\">\r\n                            <div class=\"ta-info\">\r\n                                <h6>Jina Nilson<\/h6>\r\n                            <span>Client<\/span>                     \r\n                            <\/div>\r\n                        <\/div>\r\n                        <div class=\"review-icon\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\">\r\n                         <\/div>\r\n                         <p>\u201cPhasellus aliquam quis lorem amet dapibus feugiat vitae purus vitae efficitur. Vestibulum sed elit id orci rhoncus ultricies. Morbi vitae semper consequat ipsum semper quam\u201d.<\/p>\r\n\r\n                        <div class=\"qt-img\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\">\r\n                        <\/div>\r\n                    <\/div>\r\n                                     <div class=\"single-testimonial\">\r\n                         <div class=\"testi-author\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar_02.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar_02.png\">\r\n                            <div class=\"ta-info\">\r\n                                <h6>Braitly Dcosta<\/h6>\r\n                            <span>Client<\/span>                     \r\n                            <\/div>\r\n                        <\/div>\r\n                        <div class=\"review-icon\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\">\r\n                         <\/div>\r\n                         <p>\u201cPhasellus aliquam quis lorem amet dapibus feugiat vitae purus vitae efficitur. Vestibulum sed elit id orci rhoncus ultricies. Morbi vitae semper consequat ipsum semper quam\u201d.<\/p>\r\n\r\n                        <div class=\"qt-img\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\">\r\n                        <\/div>\r\n                    <\/div>\r\n                                     <div class=\"single-testimonial\">\r\n                         <div class=\"testi-author\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar_03.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar_03.png\">\r\n                            <div class=\"ta-info\">\r\n                                <h6>Roboto Dose<\/h6>\r\n                            <span>Client<\/span>                     \r\n                            <\/div>\r\n                        <\/div>\r\n                        <div class=\"review-icon\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\">\r\n                         <\/div>\r\n                         <p>\u201cPhasellus aliquam quis lorem amet dapibus feugiat vitae purus vitae efficitur. Vestibulum sed elit id orci rhoncus ultricies. Morbi vitae semper consequat ipsum semper quam\u201d.<\/p>\r\n\r\n                        <div class=\"qt-img\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\">\r\n                        <\/div>\r\n                    <\/div>\r\n                                     <div class=\"single-testimonial\">\r\n                         <div class=\"testi-author\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar.png\">\r\n                            <div class=\"ta-info\">\r\n                                <h6>Jina Nilson<\/h6>\r\n                            <span>Client<\/span>                     \r\n                            <\/div>\r\n                        <\/div>\r\n                        <div class=\"review-icon\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\">\r\n                         <\/div>\r\n                         <p>\u201cPhasellus aliquam quis lorem amet dapibus feugiat vitae purus vitae efficitur. Vestibulum sed elit id orci rhoncus ultricies. Morbi vitae semper consequat ipsum semper quam\u201d.<\/p>\r\n\r\n                        <div class=\"qt-img\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\">\r\n                        <\/div>\r\n                    <\/div>\r\n                                     <div class=\"single-testimonial\">\r\n                         <div class=\"testi-author\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar_02.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar_02.png\">\r\n                            <div class=\"ta-info\">\r\n                                <h6>Braitly Dcosta<\/h6>\r\n                            <span>Client<\/span>                     \r\n                            <\/div>\r\n                        <\/div>\r\n                        <div class=\"review-icon\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\">\r\n                         <\/div>\r\n                         <p>\u201cPhasellus aliquam quis lorem amet dapibus feugiat vitae purus vitae efficitur. Vestibulum sed elit id orci rhoncus ultricies. Morbi vitae semper consequat ipsum semper quam\u201d.<\/p>\r\n\r\n                        <div class=\"qt-img\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\">\r\n                        <\/div>\r\n                    <\/div>\r\n                                     <div class=\"single-testimonial\">\r\n                         <div class=\"testi-author\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar_03.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/testi_avatar_03.png\">\r\n                            <div class=\"ta-info\">\r\n                                <h6>Roboto Dose<\/h6>\r\n                            <span>Client<\/span>                     \r\n                            <\/div>\r\n                        <\/div>\r\n                        <div class=\"review-icon\">\r\n                            <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/review-icon.png\">\r\n                         <\/div>\r\n                         <p>\u201cPhasellus aliquam quis lorem amet dapibus feugiat vitae purus vitae efficitur. Vestibulum sed elit id orci rhoncus ultricies. Morbi vitae semper consequat ipsum semper quam\u201d.<\/p>\r\n\r\n                        <div class=\"qt-img\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/qt-icon.png\">\r\n                        <\/div>\r\n                    <\/div>\r\n                   \r\n                <\/div>\r\n            <\/div>\r\n\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n<!-- testimonial-area-end -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a894d6e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a894d6e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b999707\" data-id=\"b999707\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f849ea elementor-widget elementor-widget-Elementor-newsletter-widget\" data-id=\"9f849ea\" data-element_type=\"widget\" data-widget_type=\"Elementor-newsletter-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- newslater-area -->\r\n<section class=\"newslater-area p-relative pt-120 pb-120\">\r\n    <div class=\"animations-01\"><img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/an-img-07.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/an-img-07.png\"><\/div>\r\n    <div class=\"container\">\r\n        <div class=\"row justify-content-center align-items-center text-center\">\r\n            <div class=\"col-xl-9 col-lg-10\">\r\n                <div class=\"section-title center-align mb-40 text-center wow fadeInDown animated\" data-animation=\"fadeInDown\" data-delay=\".4s\">\r\n                     <h5><span class=\"circle-left\"><img decoding=\"async\" src=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/circle-left.png\" alt=\"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-content\/uploads\/2023\/04\/circle-left.png\"><\/span> Newsletter<\/h5>\r\n                   <h2> Get Best Offers On The Food <\/h2>\r\n                    <p>With the subscription, enjoy your favourite coffees without having to think about it <\/p>\r\n                <\/div>\r\n                <div id=\"contact-form4\" class=\"contact-form newslater\">\r\n                   <div class=\"form-group\">\r\n                        <script>(function() {\n\twindow.mc4wp = window.mc4wp || {\n\t\tlisteners: [],\n\t\tforms: {\n\t\t\ton: function(evt, cb) {\n\t\t\t\twindow.mc4wp.listeners.push(\n\t\t\t\t\t{\n\t\t\t\t\t\tevent   : evt,\n\t\t\t\t\t\tcallback: cb\n\t\t\t\t\t}\n\t\t\t\t);\n\t\t\t}\n\t\t}\n\t}\n})();\n<\/script><!-- Mailchimp for WordPress v4.10.3 - https:\/\/wordpress.org\/plugins\/mailchimp-for-wp\/ --><form id=\"mc4wp-form-1\" class=\"mc4wp-form mc4wp-form-230\" method=\"post\" data-id=\"230\" data-name=\"newslater\" ><div class=\"mc4wp-form-fields\"><input class=\"form-control\" name=\"email\" type=\"email\" placeholder=\"Your Email Address\" value=\"\" required=\"\"> \r\n<button type=\"submit\" class=\"btn btn-custom\" id=\"send2\">Subscribe Now<\/button><\/div><label style=\"display: none !important;\">Leave this field empty if you're human: <input type=\"text\" name=\"_mc4wp_honeypot\" value=\"\" tabindex=\"-1\" autocomplete=\"off\" \/><\/label><input type=\"hidden\" name=\"_mc4wp_timestamp\" value=\"1784123751\" \/><input type=\"hidden\" name=\"_mc4wp_form_id\" value=\"230\" \/><input type=\"hidden\" name=\"_mc4wp_form_element_id\" value=\"mc4wp-form-1\" \/><div class=\"mc4wp-response\"><\/div><\/form><!-- \/ Mailchimp for WordPress Plugin -->                   <\/div>\r\n                   <!-- \/Form-email -->\t\r\n                <\/div>\r\n            <\/div>\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n<\/section>\r\n<!-- newslater-aread-end -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"inside.php","meta":{"footnotes":""},"class_list":["post-26","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-json\/wp\/v2\/pages\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":13,"href":"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-json\/wp\/v2\/pages\/26\/revisions"}],"predecessor-version":[{"id":384,"href":"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-json\/wp\/v2\/pages\/26\/revisions\/384"}],"wp:attachment":[{"href":"https:\/\/wpdemo.zcubethemes.com\/yummye\/wp-json\/wp\/v2\/media?parent=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}